{"id":8660,"date":"2024-08-29T21:12:36","date_gmt":"2024-08-30T01:12:36","guid":{"rendered":"https:\/\/www.teleclub.com.py\/?post_type=product&#038;p=8660"},"modified":"2024-08-30T18:40:24","modified_gmt":"2024-08-30T22:40:24","slug":"soporte-articulado-doble-para-monitor-sate-a-rm18t-17-a-32-hasta-9kg-negro","status":"publish","type":"product","link":"https:\/\/www.teleclub.com.py\/index.php\/product\/soporte-articulado-doble-para-monitor-sate-a-rm18t-17-a-32-hasta-9kg-negro\/","title":{"rendered":"Soporte Articulado Doble para Monitor Sate A-RM18T 17&#8243;; a 32&quot; hasta 9KG &#8211; Negro"},"content":{"rendered":"<div class=\"item content\">\n<div class=\"product attribute description\">\n<div class=\"value\">\n<div><b>Caracter\u00edsticas<\/b><\/p>\n<p>Soporte articulado de 2 brazos para monitor y Notebook.<\/p>\n<p>Compatible con pantallas (TVs o Monitores) de 17&#8243; a 32&#8243; y Notebooks desde 10&#8243; a 15.6&#8243;.<\/p>\n<p>Aumenta el espacio de escritorio utilizable.<\/p>\n<p>Altura de ambos brazos ajustables.<\/p>\n<p>VESA: 100&#215;100, 75&#215;75.<\/p>\n<p>Rango de inclinaci\u00f3n: \u00b1 45\u00b0.<\/p>\n<p>Dise\u00f1o de inclinaci\u00f3n libre: facilita el ajuste hacia adelante o hacia atr\u00e1s para una mejor visualizaci\u00f3n.<\/p>\n<p>Rango de giro: \u00b1 90\u00b0.<\/p>\n<p>Brazos giratorios: ofrecen la m\u00e1xima flexibilidad de visualizaci\u00f3n.<\/p>\n<p>Rango de rotaci\u00f3n: \u00b1 180\u00b0.<\/p>\n<p>Orientaci\u00f3n vertical y horizontal: se adapta a diferentes necesidades de visualizaci\u00f3n.<\/p>\n<p>Montaje para mesa.<\/p>\n<p>Dos opciones de montaje: abrazadera de escritorio u ojal.<\/p>\n<p>Espesor de mesa\/escritorio sugerido: 10 ~ 85 mm.<\/p>\n<p>Di\u00e1metro de ojal: 10 ~ 40 mm.<\/p>\n<p>Clip organizador de cables: ayuda a reducir el desorden para una apariencia limpia y un lugar m\u00e1s organizado.<\/p><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"tab-label-additional\" class=\"item title active\" role=\"tab\"><\/div>\n","protected":false},"excerpt":{"rendered":"<div class=\"row\"><span class=\"col col-6 col-sm-6 col-md-4 col-lg-2 col-xg-2 label\">Pulgadas: <\/span><span class=\"col col-6 col-sm-6 col-md-8 col-lg-10 col-xg-10 data\" data-th=\"Pulgadas\">17&#8243; hasta 32&#8243;<\/span><\/div>\n<div class=\"row\"><span class=\"col col-6 col-sm-6 col-md-4 col-lg-2 col-xg-2 label\">Material : <\/span><span class=\"col col-6 col-sm-6 col-md-8 col-lg-10 col-xg-10 data\" data-th=\"Material\">Acero laminado en fr\u00edo.<\/span><\/div>\n<div class=\"row\"><span class=\"col col-6 col-sm-6 col-md-4 col-lg-2 col-xg-2 label\">Color: <\/span><span class=\"col col-6 col-sm-6 col-md-8 col-lg-10 col-xg-10 data\" data-th=\"Color\">Negro<\/span><\/div>\n<div class=\"row\"><span class=\"col col-6 col-sm-6 col-md-4 col-lg-2 col-xg-2 label\">Modelo : <\/span><span class=\"col col-6 col-sm-6 col-md-8 col-lg-10 col-xg-10 data\" data-th=\"Modelo\">KVS-599<\/span><\/div>\n<div class=\"row\"><span class=\"col col-6 col-sm-6 col-md-4 col-lg-2 col-xg-2 label\">Capacidad<\/span><span class=\"col col-6 col-sm-6 col-md-8 col-lg-10 col-xg-10 data\" data-th=\"Capacidad\">: 9 kg (Por pantalla) &#8211; 4 kg por Notebook<\/span><\/div>\n<div class=\"row\"><span class=\"col col-6 col-sm-6 col-md-4 col-lg-2 col-xg-2 label\">Marca: <\/span><span class=\"col col-6 col-sm-6 col-md-8 col-lg-10 col-xg-10 data\" data-th=\"Marca\">Kolke<\/span><\/div>\n<div class=\"row\"><span class=\"col col-6 col-sm-6 col-md-4 col-lg-2 col-xg-2 label\">Peso :<\/span><span class=\"col col-6 col-sm-6 col-md-8 col-lg-10 col-xg-10 data\" data-th=\"Peso\">Embalaje 5.217g<\/span><\/div>\n<div class=\"row\"><span class=\"col col-6 col-sm-6 col-md-4 col-lg-2 col-xg-2 label\">Dimensiones :<\/span><span class=\"col col-6 col-sm-6 col-md-8 col-lg-10 col-xg-10 data\" data-th=\"Dimensiones\">Embalaje 297 x 446 x 113mm<\/span><\/div>\n","protected":false},"featured_media":8661,"template":"","meta":{"om_disable_all_campaigns":false},"product_cat":[359],"product_tag":[],"class_list":["post-8660","product","type-product","status-publish","has-post-thumbnail","product_cat-accesorios-informatica-electronica","first","instock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Soporte Articulado Doble para Monitor Sate A-RM18T 17&quot;; a 32&quot; hasta 9KG - Negro - Teleclub<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.teleclub.com.py\/index.php\/product\/soporte-articulado-doble-para-monitor-sate-a-rm18t-17-a-32-hasta-9kg-negro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soporte Articulado Doble para Monitor Sate A-RM18T 17&quot;; a 32&quot; hasta 9KG - Negro - Teleclub\" \/>\n<meta property=\"og:description\" content=\"Pulgadas: 17&quot; hasta 32&quot; Material : Acero laminado en fr\u00edo. Color: Negro Modelo : KVS-599 Capacidad: 9 kg (Por pantalla) - 4 kg por Notebook Marca: Kolke Peso :Embalaje 5.217g Dimensiones :Embalaje 297 x 446 x 113mm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.teleclub.com.py\/index.php\/product\/soporte-articulado-doble-para-monitor-sate-a-rm18t-17-a-32-hasta-9kg-negro\/\" \/>\n<meta property=\"og:site_name\" content=\"Teleclub\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/teleclubpy\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-30T22:40:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.teleclub.com.py\/wp-content\/uploads\/2024\/08\/a-327.png\" \/>\n\t<meta property=\"og:image:width\" content=\"271\" \/>\n\t<meta property=\"og:image:height\" content=\"226\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.teleclub.com.py\/index.php\/product\/soporte-articulado-doble-para-monitor-sate-a-rm18t-17-a-32-hasta-9kg-negro\/\",\"url\":\"https:\/\/www.teleclub.com.py\/index.php\/product\/soporte-articulado-doble-para-monitor-sate-a-rm18t-17-a-32-hasta-9kg-negro\/\",\"name\":\"Soporte Articulado Doble para Monitor Sate A-RM18T 17\\\"; a 32&quot; hasta 9KG - Negro - Teleclub\",\"isPartOf\":{\"@id\":\"https:\/\/www.teleclub.com.py\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.teleclub.com.py\/index.php\/product\/soporte-articulado-doble-para-monitor-sate-a-rm18t-17-a-32-hasta-9kg-negro\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.teleclub.com.py\/index.php\/product\/soporte-articulado-doble-para-monitor-sate-a-rm18t-17-a-32-hasta-9kg-negro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.teleclub.com.py\/wp-content\/uploads\/2024\/08\/a-327.png\",\"datePublished\":\"2024-08-30T01:12:36+00:00\",\"dateModified\":\"2024-08-30T22:40:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.teleclub.com.py\/index.php\/product\/soporte-articulado-doble-para-monitor-sate-a-rm18t-17-a-32-hasta-9kg-negro\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.teleclub.com.py\/index.php\/product\/soporte-articulado-doble-para-monitor-sate-a-rm18t-17-a-32-hasta-9kg-negro\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.teleclub.com.py\/index.php\/product\/soporte-articulado-doble-para-monitor-sate-a-rm18t-17-a-32-hasta-9kg-negro\/#primaryimage\",\"url\":\"https:\/\/www.teleclub.com.py\/wp-content\/uploads\/2024\/08\/a-327.png\",\"contentUrl\":\"https:\/\/www.teleclub.com.py\/wp-content\/uploads\/2024\/08\/a-327.png\",\"width\":271,\"height\":226},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.teleclub.com.py\/index.php\/product\/soporte-articulado-doble-para-monitor-sate-a-rm18t-17-a-32-hasta-9kg-negro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.teleclub.com.py\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.teleclub.com.py\/index.php\/shop-2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Soporte Articulado Doble para Monitor Sate A-RM18T 17&#8243;; a 32&quot; hasta 9KG &#8211; Negro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.teleclub.com.py\/#website\",\"url\":\"https:\/\/www.teleclub.com.py\/\",\"name\":\"Teleclub\",\"description\":\"Tu tienda online\",\"publisher\":{\"@id\":\"https:\/\/www.teleclub.com.py\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.teleclub.com.py\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.teleclub.com.py\/#organization\",\"name\":\"Teleclub\",\"url\":\"https:\/\/www.teleclub.com.py\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.teleclub.com.py\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.teleclub.com.py\/wp-content\/uploads\/2024\/09\/1611317346760_TeleClub_logo_FondoBlanco-2.jpg\",\"contentUrl\":\"https:\/\/www.teleclub.com.py\/wp-content\/uploads\/2024\/09\/1611317346760_TeleClub_logo_FondoBlanco-2.jpg\",\"width\":1600,\"height\":1600,\"caption\":\"Teleclub\"},\"image\":{\"@id\":\"https:\/\/www.teleclub.com.py\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/teleclubpy\",\"https:\/\/www.instagram.com\/teleclubpy\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Soporte Articulado Doble para Monitor Sate A-RM18T 17\"; a 32&quot; hasta 9KG - Negro - Teleclub","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.teleclub.com.py\/index.php\/product\/soporte-articulado-doble-para-monitor-sate-a-rm18t-17-a-32-hasta-9kg-negro\/","og_locale":"es_ES","og_type":"article","og_title":"Soporte Articulado Doble para Monitor Sate A-RM18T 17\"; a 32&quot; hasta 9KG - Negro - Teleclub","og_description":"Pulgadas: 17\" hasta 32\" Material : Acero laminado en fr\u00edo. Color: Negro Modelo : KVS-599 Capacidad: 9 kg (Por pantalla) - 4 kg por Notebook Marca: Kolke Peso :Embalaje 5.217g Dimensiones :Embalaje 297 x 446 x 113mm","og_url":"https:\/\/www.teleclub.com.py\/index.php\/product\/soporte-articulado-doble-para-monitor-sate-a-rm18t-17-a-32-hasta-9kg-negro\/","og_site_name":"Teleclub","article_publisher":"https:\/\/www.facebook.com\/teleclubpy","article_modified_time":"2024-08-30T22:40:24+00:00","og_image":[{"width":271,"height":226,"url":"https:\/\/www.teleclub.com.py\/wp-content\/uploads\/2024\/08\/a-327.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.teleclub.com.py\/index.php\/product\/soporte-articulado-doble-para-monitor-sate-a-rm18t-17-a-32-hasta-9kg-negro\/","url":"https:\/\/www.teleclub.com.py\/index.php\/product\/soporte-articulado-doble-para-monitor-sate-a-rm18t-17-a-32-hasta-9kg-negro\/","name":"Soporte Articulado Doble para Monitor Sate A-RM18T 17\"; a 32&quot; hasta 9KG - Negro - Teleclub","isPartOf":{"@id":"https:\/\/www.teleclub.com.py\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.teleclub.com.py\/index.php\/product\/soporte-articulado-doble-para-monitor-sate-a-rm18t-17-a-32-hasta-9kg-negro\/#primaryimage"},"image":{"@id":"https:\/\/www.teleclub.com.py\/index.php\/product\/soporte-articulado-doble-para-monitor-sate-a-rm18t-17-a-32-hasta-9kg-negro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.teleclub.com.py\/wp-content\/uploads\/2024\/08\/a-327.png","datePublished":"2024-08-30T01:12:36+00:00","dateModified":"2024-08-30T22:40:24+00:00","breadcrumb":{"@id":"https:\/\/www.teleclub.com.py\/index.php\/product\/soporte-articulado-doble-para-monitor-sate-a-rm18t-17-a-32-hasta-9kg-negro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.teleclub.com.py\/index.php\/product\/soporte-articulado-doble-para-monitor-sate-a-rm18t-17-a-32-hasta-9kg-negro\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.teleclub.com.py\/index.php\/product\/soporte-articulado-doble-para-monitor-sate-a-rm18t-17-a-32-hasta-9kg-negro\/#primaryimage","url":"https:\/\/www.teleclub.com.py\/wp-content\/uploads\/2024\/08\/a-327.png","contentUrl":"https:\/\/www.teleclub.com.py\/wp-content\/uploads\/2024\/08\/a-327.png","width":271,"height":226},{"@type":"BreadcrumbList","@id":"https:\/\/www.teleclub.com.py\/index.php\/product\/soporte-articulado-doble-para-monitor-sate-a-rm18t-17-a-32-hasta-9kg-negro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.teleclub.com.py\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.teleclub.com.py\/index.php\/shop-2\/"},{"@type":"ListItem","position":3,"name":"Soporte Articulado Doble para Monitor Sate A-RM18T 17&#8243;; a 32&quot; hasta 9KG &#8211; Negro"}]},{"@type":"WebSite","@id":"https:\/\/www.teleclub.com.py\/#website","url":"https:\/\/www.teleclub.com.py\/","name":"Teleclub","description":"Tu tienda online","publisher":{"@id":"https:\/\/www.teleclub.com.py\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.teleclub.com.py\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.teleclub.com.py\/#organization","name":"Teleclub","url":"https:\/\/www.teleclub.com.py\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.teleclub.com.py\/#\/schema\/logo\/image\/","url":"https:\/\/www.teleclub.com.py\/wp-content\/uploads\/2024\/09\/1611317346760_TeleClub_logo_FondoBlanco-2.jpg","contentUrl":"https:\/\/www.teleclub.com.py\/wp-content\/uploads\/2024\/09\/1611317346760_TeleClub_logo_FondoBlanco-2.jpg","width":1600,"height":1600,"caption":"Teleclub"},"image":{"@id":"https:\/\/www.teleclub.com.py\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/teleclubpy","https:\/\/www.instagram.com\/teleclubpy"]}]}},"_links":{"self":[{"href":"https:\/\/www.teleclub.com.py\/index.php\/wp-json\/wp\/v2\/product\/8660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.teleclub.com.py\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.teleclub.com.py\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.teleclub.com.py\/index.php\/wp-json\/wp\/v2\/media\/8661"}],"wp:attachment":[{"href":"https:\/\/www.teleclub.com.py\/index.php\/wp-json\/wp\/v2\/media?parent=8660"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.teleclub.com.py\/index.php\/wp-json\/wp\/v2\/product_cat?post=8660"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.teleclub.com.py\/index.php\/wp-json\/wp\/v2\/product_tag?post=8660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}